{"id":1194,"date":"2019-06-11T12:05:09","date_gmt":"2019-06-11T10:05:09","guid":{"rendered":"https:\/\/cabanes-de-provence.com\/?post_type=mphb_room_type&#038;p=1194"},"modified":"2026-07-09T15:30:27","modified_gmt":"2026-07-09T13:30:27","slug":"a-cabana-secreta","status":"publish","type":"mphb_room_type","link":"https:\/\/cabanes-de-provence.com\/pt\/accommodation\/le-cabanon-des-secrets\/","title":{"rendered":"A Cabanon des Secrets"},"content":{"rendered":"<h2>Le Cabanon des Secrets<\/h2>\n<p><em>D\u00e9couvrez le site internet d\u00e9di\u00e9 : <a href=\"https:\/\/cabanon-des-secrets.fr\" target=\"_blank\" rel=\"noopener\">www.cabanon-des-secrets.fr<\/a><\/em><\/p>\n<p>Le Cabanon des Secrets a \u00e9t\u00e9 enti\u00e8rement r\u00e9nov\u00e9 dans les r\u00e8gles de l\u2019art. Cette ancienne b\u00e2tisse a su garder son charme ancestral avec ses fa\u00e7ades en pierre, ses poutres apparentes patin\u00e9es et son jardin en restanque. Perch\u00e9 sur les Monts de Vaucluse ce village pittoresque creus\u00e9 dans la roche a tout pour vous enchanter. Avec ces petites ruelles calad\u00e9es, son historique ch\u00e2teau et sa belle \u00e9glise datant du onzi\u00e8me si\u00e8cle, d\u00e9couvrez la Provence la plus authentique.<\/p>\n<p>Accommodant jusqu\u2019\u00e0 quatre personnes, cet authentique cabanon offre un confort unique dans un lieu d\u2019exception. En plus d\u2019\u00eatre tout \u00e9quip\u00e9, un SPA priv\u00e9 et chauff\u00e9 est \u00e0 votre disposition.<\/p>\n<p><span style=\"color: #fff !important; background-color: #F5887D; padding: 3px 15px 2px 15px; border-radius: 10px;\">[Important] Forfait m\u00e9nage et entretien en fin de s\u00e9jour : 60\u20ac.<\/span><\/p>\n<h4><strong>\u00c9quipement :<\/strong><\/h4>\n<p>Tout a \u00e9t\u00e9 r\u00e9fl\u00e9chi pour que le s\u00e9jour des h\u00f4tes ne soit qu\u2019enchantement et le cabanon a \u00e9t\u00e9 sp\u00e9cialement r\u00e9nov\u00e9 pour vous immerger dans une ambiance pittoresque. Le jardin \u00e0 la proven\u00e7ale et son terrain de p\u00e9tanque privatis\u00e9s sont \u00e0 votre disposition pendant toute la dur\u00e9e de votre s\u00e9jour. La vue de la terrasse est panoramique et un SPA priv\u00e9 et chauff\u00e9 en toutes saisons permettra aux h\u00f4tes de se relaxer en admirant la beaut\u00e9 du site.<br \/>\nSalle de bains, douche \u00e0 l\u2019italienne, toilettes s\u00e9par\u00e9es, cuisine ind\u00e9pendante, dressing, deux chambres avec lit double, Wifi, jardin en restanque et SPA ext\u00e9rieur chauff\u00e9.<br \/>\nLe cabanon est \u00e9quip\u00e9 de climatisation r\u00e9versible.<\/p>\n<h4><strong>Linges de maison :<\/strong><\/h4>\n<p>Draps et linge de toilettes fournis.<br \/>\nLes dessus de lits, rideaux \u00e9tant de qualit\u00e9, toute d\u00e9gradation ou salissure donnera lieu \u00e0 un d\u00e9dommagement.<\/p>\n<h4><strong>Informations pratiques :<\/strong><\/h4>\n<p>La remise des clefs du cabanon a lieu entre 16h00 et 19h mais une entr\u00e9e en autonomie est possible.<br \/>\nLe cabanon doit \u00eatre lib\u00e9r\u00e9 au plus tard \u00e0 11h le jour du d\u00e9part.<br \/>\nLes clients devront respecter le caract\u00e8re paisible des lieux, les v\u00e9hicules seront stationn\u00e9s sur le parking.<br \/>\nLes animaux ne sont pas admis.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Cabanon des Secrets \u00e9 uma aut\u00eantica cabana de pedra que oferece conforto \u00fanico em um cen\u00e1rio excepcional para 4 pessoas. Al\u00e9m de estar totalmente equipada, uma banheira de hidromassagem privativa e aquecida est\u00e1 \u00e0 sua disposi\u00e7\u00e3o.<\/p>\n<p><a class=\"btn_room\" href=\"https:\/\/book.cabanes-de-provence.com\/listings\/502056?numberOfGuests=1\" target=\"_blank\">Para reservar<\/a><\/p>","protected":false},"featured_media":1115,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"16724","mphb_room_type_category":[35],"mphb_room_type_tag":[],"mphb_room_type_facility":[46,28,34,32,36,45,31,30],"class_list":["post-1194","mphb_room_type","type-mphb_room_type","status-publish","has-post-thumbnail","hentry","mphb_room_type_category-cabanon","mphb_room_type_facility-barbecue","mphb_room_type_facility-climatisation","mphb_room_type_facility-cuisine","mphb_room_type_facility-douche","mphb_room_type_facility-dressing","mphb_room_type_facility-jardin-en-restanque","mphb_room_type_facility-spa","mphb_room_type_facility-wifi","mphb-room-type-adults-4","mphb-room-type-children-4",""],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cabanes-de-provence.com\/pt\/wp-json\/wp\/v2\/mphb_room_type\/1194","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cabanes-de-provence.com\/pt\/wp-json\/wp\/v2\/mphb_room_type"}],"about":[{"href":"https:\/\/cabanes-de-provence.com\/pt\/wp-json\/wp\/v2\/types\/mphb_room_type"}],"replies":[{"embeddable":true,"href":"https:\/\/cabanes-de-provence.com\/pt\/wp-json\/wp\/v2\/comments?post=1194"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cabanes-de-provence.com\/pt\/wp-json\/wp\/v2\/media\/1115"}],"wp:attachment":[{"href":"https:\/\/cabanes-de-provence.com\/pt\/wp-json\/wp\/v2\/media?parent=1194"}],"wp:term":[{"taxonomy":"mphb_room_type_category","embeddable":true,"href":"https:\/\/cabanes-de-provence.com\/pt\/wp-json\/wp\/v2\/mphb_room_type_category?post=1194"},{"taxonomy":"mphb_room_type_tag","embeddable":true,"href":"https:\/\/cabanes-de-provence.com\/pt\/wp-json\/wp\/v2\/mphb_room_type_tag?post=1194"},{"taxonomy":"mphb_room_type_facility","embeddable":true,"href":"https:\/\/cabanes-de-provence.com\/pt\/wp-json\/wp\/v2\/mphb_room_type_facility?post=1194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}