{"id":15192,"date":"2021-07-21T12:58:05","date_gmt":"2021-07-21T10:58:05","guid":{"rendered":"https:\/\/cabanes-de-provence.com\/?page_id=15192"},"modified":"2026-05-28T10:49:33","modified_gmt":"2026-05-28T08:49:33","slug":"opcoes","status":"publish","type":"page","link":"https:\/\/cabanes-de-provence.com\/pt\/options\/","title":{"rendered":"Nossos servi\u00e7os sob demanda"},"content":{"rendered":"<p style=\"text-align: center;\">Oferecemos diversos servi\u00e7os para domic\u00edlio, como kits de aperitivos, massagens personalizadas, um pacote &quot;O Grande Jogo&quot; para casais, recomenda\u00e7\u00f5es tur\u00edsticas, prepara\u00e7\u00e3o de caf\u00e9 da manh\u00e3 e entrega de produtos frescos.<\/p>\n<p style=\"text-align: center;\">Consulte-nos ou fa\u00e7a sua reserva diretamente online, escolhendo as op\u00e7\u00f5es desejadas.<\/p>\n\n\n<div class=\"wp-block-getwid-section color_box\"><div class=\"wp-block-getwid-section__wrapper getwid-padding-top-small getwid-padding-bottom-medium\"><div class=\"wp-block-getwid-section__inner-wrapper\"><div class=\"wp-block-getwid-section__background-holder\"><div class=\"wp-block-getwid-section__background has-background\" style=\"background-color:#cfbe92\"><\/div><div class=\"wp-block-getwid-section__foreground\"><\/div><\/div><div class=\"wp-block-getwid-section__content\"><div class=\"wp-block-getwid-section__inner-content\">\n<div class=\"wp-block-getwid-advanced-heading is-style-style-1\" style=\"margin-bottom:20px\"><span class=\"wp-block-getwid-advanced-heading__content\" style=\"text-align:center\">TODOS OS SERVI\u00c7OS DAS NOSSAS CASAS DE F\u00c9RIAS NA PROV\u00c9NCIA<br><strong>NO SEU PORTAL DE VIAJANTE<\/strong><br><\/span><\/div>\n\n\n\n<p style=\"text-align: center;\"><span style=\"color: #333333;\">Para reservar seus servi\u00e7os, acesse diretamente o seu perfil. <strong>Portal do Viajante<\/strong> o link que lhe foi enviado por e-mail ap\u00f3s a sua reserva.\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #333333;\">At\u00e9 breve na Proven\u00e7a!<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Nous offrons de nombreux services \u00e0 domicile tels que des ap\u00e9ros box, des massages sur-mesure, un pack \u00ab\u00a0Le Grand Jeu\u00a0\u00bb pour les amoureux, des recommandations touristiques ou encore la pr\u00e9paration de petits d\u00e9jeuners et la livraison de produits frais. Consultez-nous ou r\u00e9server directement en ligne en choisissant vos options.<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-front-page.php","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"class_list":["post-15192","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cabanes-de-provence.com\/pt\/wp-json\/wp\/v2\/pages\/15192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cabanes-de-provence.com\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cabanes-de-provence.com\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cabanes-de-provence.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cabanes-de-provence.com\/pt\/wp-json\/wp\/v2\/comments?post=15192"}],"version-history":[{"count":13,"href":"https:\/\/cabanes-de-provence.com\/pt\/wp-json\/wp\/v2\/pages\/15192\/revisions"}],"predecessor-version":[{"id":16710,"href":"https:\/\/cabanes-de-provence.com\/pt\/wp-json\/wp\/v2\/pages\/15192\/revisions\/16710"}],"wp:attachment":[{"href":"https:\/\/cabanes-de-provence.com\/pt\/wp-json\/wp\/v2\/media?parent=15192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}